{"id":1216,"date":"2019-12-05T14:39:09","date_gmt":"2019-12-05T14:39:09","guid":{"rendered":"https:\/\/staging.cerakote.co.uk\/?post_type=product&#038;p=1216"},"modified":"2026-06-30T18:08:12","modified_gmt":"2026-06-30T18:08:12","slug":"magpul-foliage-green-c-231","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/it\/product\/magpul-foliage-green-c-231\/","title":{"rendered":"MagPul\u2122 Foliage Green C-231"},"content":{"rendered":"<section class=\"section\" id=\"section_1358570532\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1946747661\">\n\n\t<div id=\"col-1708083866\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong>Dati tecnici del prodotto:<\/strong><\/p>\n<p><style>\n.table_component {<br \/>\n    overflow: auto;<br \/>\n    width: 100%;<br \/>\n}<\/p>\n<p>.table_component table {<br \/>\n    border: 1px solid #dededf;<br \/>\n    height: 100%;<br \/>\n    width: 100%;<br \/>\n    table-layout: fixed;<br \/>\n    border-collapse: collapse;<br \/>\n    border-spacing: 1px;<br \/>\n    text-align: left;<br \/>\n}<\/p>\n<p>.table_component caption {<br \/>\n    caption-side: top;<br \/>\n    text-align: left;<br \/>\n}<\/p>\n<p>.table_component th {<br \/>\n    border: 1px solid #dededf;<br \/>\n    background-color: #eceff1;<br \/>\n    color: #000000;<br \/>\n    padding: 5px;<br \/>\n}<\/p>\n<p>.table_component td {<br \/>\n    border: 1px solid #dededf;<br \/>\n    background-color: #ffffff;<br \/>\n    color: #000000;<br \/>\n    padding: 5px;<br \/>\n}<br \/>\n<\/style>\n<\/p>\n<div class=\"table_component\" tabindex=\"0\" role=\"region\">\n<table>\n<thead>\n<tr>\n<th>\u00a0<\/th>\n<th>\u00a0<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Programma di cura\u00a0<\/td>\n<td>\n<p class=\"p2\">Air Cure: Tack Free 45 &#8211; 60 minutes, Full Cure 5Days<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Spessore consigliato (mil)<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Dimensione del filtro (maglia)<\/td>\n<td>150 (parte # SE-276)<\/td>\n<\/tr>\n<tr>\n<td>Livello di lucentezza \/ Unit\u00e0 (GU)<\/td>\n<td>Flat \/ 3<\/td>\n<\/tr>\n<tr>\n<td>Densit\u00e0 (g\/mL)<\/td>\n<td>1.40<\/td>\n<\/tr>\n<tr>\n<td>% Solidi (\u00b12%)<\/td>\n<td>51<\/td>\n<\/tr>\n<tr>\n<td>Viscosit\u00e0 (cP)<\/td>\n<td>40<\/td>\n<\/tr>\n<tr>\n<td>Copertura teorica per gal a spessore consigliato (ft\u00b2)<\/td>\n<td>812<\/td>\n<tr>\n<td>Stabilit\u00e0 del colore (\u00b0F) Temperatura massima Temp.<\/td>\n<td>500<\/td>\n<\/tr>\n<tr>\n<td>Resistenza chimica<\/td>\n<td>Eccellente<\/td>\n<\/tr>\n<tr>\n<td>Stabilit\u00e0 UV<\/td>\n<td>Eccellente<\/td>\n<\/tr>\n<tr>\n<td>Durezza della matita Sgorbia ASTM D3363<\/td>\n<td>5H<\/td>\n<\/tr>\n<tr>\n<td>Durezza della matita Graffio ASTM D3363<\/td>\n<td>5H<\/td>\n<\/tr>\n<tr>\n<td>Adesione trasversale ASTM D3359<\/td>\n<td>\n<p>5B<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Flessibilit\u00e0 (resistenza %) Curvatura conica ASTM D522<\/td>\n<td>\n<p>98<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Prestazioni d'impatto dirette\/indirette (in-lbs) ASTM D2794<\/td>\n<td>60\/0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p data-v-8ef39626=\"\">Tutti i risultati si basano su acciaio sabbiato rivestito con lo spessore consigliato e con il programma di polimerizzazione raccomandato.<\/p>\n<p data-v-8ef39626=\"\">*I livelli di lucentezza sono misurati con un angolo di 60\u00b0. Se si modificano le condizioni raccomandate si otterranno risultati diversi. La brillantezza \u00e8 influenzata dalla qualit\u00e0 della preparazione e dalla tecnica di spruzzatura. I risultati si basano su acciaio sabbiato rivestito e polimerizzato secondo le specifiche del programma di polimerizzazione.<\/p>\n<p data-v-8ef39626=\"\">**Viscosit\u00e0 misurata in condizioni ambientali (temperatura dell'aria, umidit\u00e0 relativa) al momento della produzione.<\/p>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Temperatura di polimerizzazione consigliata:<\/strong><\/p>\n<ul data-v-8ef39626=\"\">\n<li data-v-8ef39626=\"\">Fare riferimento alle specifiche del programma di polimerizzazione disponibili su ciascun prodotto Cerakote.<\/li>\n<\/ul>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Temperatura massima<\/strong>\u00a0\u00e8 la temperatura a cui il colore o il rivestimento \u00e8 stabile.<\/p>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Test di resistenza chimica:<\/strong>\u00a0I risultati si riferiscono alla variazione di colore in base alla formulazione CIE76. I risultati variano da:<\/p>\n<ul data-v-8ef39626=\"\">\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Eccellente:<\/strong>\u00a0Variazione \u2206E di &lt;2,5<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Bene:<\/strong>\u00a0Variazione \u2206E di &lt;3,0<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Fiera:<\/strong>\u00a0Variazione \u2206E di &lt;3,5<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Povero:<\/strong>\u00a0Variazione \u2206E di &lt;4,0<\/li>\n<\/ul>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">I parametri di prova sono i seguenti:<\/strong><\/p>\n<ul data-v-8ef39626=\"\">\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Durezza<\/strong>\u00a0I test di durezza delle matite sono misurati dal pi\u00f9 morbido al pi\u00f9 duro come segue: 9B, 8B, 7B, 6B, 5B, 4B, 3B, 2B, B, HB, F, H, 2H, 3H, 4H, 5H, 6H, 7H, 8H, 9H. Il 9H \u00e8 il pi\u00f9 difficile.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">SOLO SG-100:<\/strong>\u00a0Prova di durezza Metodo A - Si esegue un taglio a X attraverso il film fino al substrato, si applica un nastro adesivo sensibile alla pressione sul taglio e poi lo si rimuove, e si valuta l'adesione in modo qualitativo su una scala da 0 a 5.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Adesione<\/strong>\u00a0\u00e8 misurato su una scala di 0B, 1B, 2B, 3B, 4B, 5B, con 5B che rappresenta il massimo punteggio raggiungibile.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Flessibilit\u00e0<\/strong>\u00a0o Curvatura conica: \"100% Resistance\" \u00e8 la valutazione pi\u00f9 alta ottenibile e indica che il rivestimento non si \u00e8 incrinato o scheggiato.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Impatto Prestazioni (dirette\/indirette)<\/strong>\u00a0\u00e8 misurato su una scala da 0 a 160 pollici-libbre, con 160 pollici-libbre come valore massimo raggiungibile.<\/li>\n<\/ul>\n<p data-v-8ef39626=\"\">Tutti i rivestimenti Cerakote sono conformi ai requisiti VOC dell'EPA e hanno un contenuto di VOC basso o nullo. Per conoscere il contenuto di VOC di un singolo rivestimento, si prega di contattare\u00a0<a href=\"mailto:sds@nicindustries.com\" target=\"_blank\" rel=\"noopener\" data-v-8ef39626=\"\">sds@nicindustries.com<\/a>\u00a0per maggiori informazioni.<\/p>\n<p data-v-8ef39626=\"\">Queste informazioni sono accurate al meglio delle nostre conoscenze, tuttavia non costituiscono una garanzia per nessuna caratteristica specifica del prodotto e non stabiliscono un rapporto contrattuale legalmente valido. Si consiglia di eseguire test adeguati nella propria struttura per determinare se questo prodotto soddisfa tutti i requisiti.<\/p>\n<p data-v-8ef39626=\"\">Non esitate a contattarci via e-mail all'indirizzo <a href=\"mailto:enquiries@cerakoteeu.com\" target=\"_blank\" rel=\"noopener\" data-v-8ef39626=\"\">enquiries@cerakoteeu.com<\/a>\u00a0 se avete domande.<\/p>\n<\/div>\n<div class=\"row\"  id=\"row-919004260\">\n\n\t<div id=\"col-296184774\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/images.nicindustries.com\/cerakote\/documents\/6998\/cerakote-c-series-dt20241219191346710211.pdf?1734635628&#038;_gl=1*17xq0fw*_gcl_au*MTA5MjM2ODk3NS4xNzUwMzE5ODc4*_ga*MTk4NjI1NzI1OC4xNzAzMTU2NTIz*_ga_KPM5Q2PRTX*czE3NTM0Mjk3NzgkbzM4JGcxJHQxNzUzNDMxMjg3JGo2MCRsMCRoMjMyNjIzNjk4\" target=\"_blank\" class=\"button primary\" rel=\"noopener\" >\n\t\t<span>Scheda di sicurezza<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1563095495\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/images.nicindustries.com\/cerakote\/documents\/7366\/c-series-training-manual-air-cure-dt2025052120523612731.pdf?1747860761&#038;_gl=1*1jpg8b3*_gcl_au*MTA5MjM2ODk3NS4xNzUwMzE5ODc4*_ga*MTk4NjI1NzI1OC4xNzAzMTU2NTIz*_ga_KPM5Q2PRTX*czE3NTM0Mjk3NzgkbzM4JGcxJHQxNzUzNDMxMjk1JGo1MiRsMCRoMjMyNjIzNjk4\" target=\"_blank\" class=\"button primary\" rel=\"noopener\" >\n\t\t<span>Guida all'applicazione<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2095331626\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/www.cerakoteeu.com\/wp-content\/uploads\/2025\/07\/C-231-Magpul-Foliage-Green.pdf\" target=\"_blank\" class=\"button primary\" rel=\"noopener\" >\n\t\t<span>Scheda tecnica<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1358570532 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"<p>Il Cerakote MagPul\u2122 Foliage Green \u00e8 di colore verde oliva chiaro con sfumature marrone.<\/p>\n<p>*NOTA: questo prodotto non richiede catalizzatore. Questo colore richiede un <a href=\"https:\/\/www.cerakoteeu.com\/product\/cerakote-in-cup-150-mesh-strainer-100-micron-se-276\/\">Filtro a 150 maglie<\/a> (SE-276).<\/p>\n<p>I rivestimenti ceramici Cerakote MagPul\u2122 Foliage Green della Serie C funzionano a temperature fino a 1.800\u00b0F \/ 982\u00b0C e definiscono lo standard industriale dei rivestimenti per alte temperature. I rivestimenti della Serie C sono una linea di rivestimenti ceramici polimerizzati in aria e pronti per la spruzzatura. Scoprite il <a href=\"https:\/\/www.cerakoteeu.com\/documents\/\">Risorse<\/a> per le guide all'applicazione dei prodotti, le schede tecniche e le informazioni SDS.<\/p>","protected":false},"featured_media":6059,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1120,987,1121,1124,1123,1122],"product_tag":[488,59,33,43,489],"class_list":["post-1216","product","type-product","status-publish","has-post-thumbnail","product_cat-c-series-coatings","product_cat-cerakote-coatings","product_cat-1000c","product_cat-up-to-260c","product_cat-up-to-425c","product_cat-650c","product_tag-c-231","product_tag-c-series","product_tag-cerakote","product_tag-green","product_tag-magpul-foliage-green","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/product\/1216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/comments?post=1216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/media\/6059"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/media?parent=1216"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/product_brand?post=1216"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/product_cat?post=1216"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/it\/wp-json\/wp\/v2\/product_tag?post=1216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}