{"id":490,"date":"2019-12-04T08:48:41","date_gmt":"2019-12-04T08:48:41","guid":{"rendered":"https:\/\/staging.cerakote.co.uk\/?post_type=product&#038;p=490"},"modified":"2026-06-30T17:44:06","modified_gmt":"2026-06-30T17:44:06","slug":"northern-lights-h-315","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/fr\/product\/northern-lights-h-315\/","title":{"rendered":"Northern Lights H-315"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cerakote Northern Lights est un bleu marine aux couleurs changeantes qui se transforme en sarcelle verd\u00e2tre avec des m\u00e9tallis\u00e9s dor\u00e9s scintillants.<\/p>\n<p>*REMARQUE : ce produit est livr\u00e9 avec un catalyseur et n\u00e9cessite un\u00a0<a href=\"https:\/\/www.cerakoteeu.com\/shop\/equipment\/cerakote-in-cup-100-mesh-strainer-150-micron-se-275\/\">Filtre de 100 mailles (SE-275)<\/a>.<\/p>\n<p>Les rev\u00eatements Cerakote de la s\u00e9rie H r\u00e9sistent durablement \u00e0 la corrosion et offrent des niveaux de duret\u00e9 et d'adh\u00e9rence in\u00e9gal\u00e9s. Ces rev\u00eatements sont \u00e9galement r\u00e9sistants \u00e0 la plupart des solvants et des produits chimiques. Les rev\u00eatements Cerakote de la s\u00e9rie H reposent sur une technologie c\u00e9ramique unique qui conf\u00e8re au rev\u00eatement final \u00e0 la fois souplesse et excellente r\u00e9sistance \u00e0 l'usure. D\u00e9couvrez les rev\u00eatements de la s\u00e9rie H de Cerakote <a href=\"https:\/\/www.cerakoteeu.com\/documents\/\">Ressources<\/a> pour obtenir des guides d'application des produits, des fiches techniques et des informations sur les FDS.<\/p>","protected":false},"featured_media":18097,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[37],"product_tag":[33,36,198,199,200],"class_list":["post-490","product","type-product","status-publish","has-post-thumbnail","product_cat-h-series-coatings","product_tag-cerakote","product_tag-h-series","product_tag-h-315","product_tag-h315","product_tag-navy-blue","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/product\/490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/comments?post=490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/media\/18097"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/media?parent=490"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/product_brand?post=490"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/product_cat?post=490"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/fr\/wp-json\/wp\/v2\/product_tag?post=490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}