{"id":689,"date":"2019-12-04T12:08:21","date_gmt":"2019-12-04T12:08:21","guid":{"rendered":"https:\/\/staging.cerakote.co.uk\/?post_type=product&#038;p=689"},"modified":"2026-06-30T17:42:06","modified_gmt":"2026-06-30T17:42:06","slug":"magpul-foliage-green-h-231","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/es\/product\/magpul-foliage-green-h-231\/","title":{"rendered":"MagPul\u2122 Foliage Green H-231"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cerakote MagPul\u2122 Foliage Green es un verde oliva.<\/p>\n<p>*NOTA: Este producto viene con un catalizador y requiere un\u00a0<a href=\"https:\/\/www.cerakoteeu.com\/product\/cerakote-in-cup-150-mesh-strainer-100-micron-se-276\/\">Colador de malla 150 (SE-276)<\/a>.<\/p>\n<p>Los recubrimientos Cerakote Serie H son resistentes a la corrosi\u00f3n duradera y proporcionan niveles incomparables de dureza y adherencia. Estos recubrimientos tambi\u00e9n son resistentes a la mayor\u00eda de disolventes y productos qu\u00edmicos. La base de los recubrimientos Cerakote Serie H es una tecnolog\u00eda cer\u00e1mica exclusiva que confiere flexibilidad y una excelente resistencia al desgaste al recubrimiento final. Eche un vistazo a la <a href=\"https:\/\/www.cerakoteeu.com\/documents\/\">Recursos<\/a> para obtener gu\u00edas de aplicaci\u00f3n de productos, fichas t\u00e9cnicas e informaci\u00f3n SDS.<\/p>","protected":false},"featured_media":18116,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[37],"product_tag":[43,328,329,330,331],"class_list":["post-689","product","type-product","status-publish","has-post-thumbnail","product_cat-h-series-coatings","product_tag-green","product_tag-h-231","product_tag-h-series-cerakote","product_tag-h231","product_tag-magpul-foliage-green-2","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/comments?post=689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media\/18116"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media?parent=689"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_brand?post=689"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_cat?post=689"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_tag?post=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}