{"id":484,"date":"2019-12-04T08:44:27","date_gmt":"2019-12-04T08:44:27","guid":{"rendered":"https:\/\/staging.cerakote.co.uk\/?post_type=product&#038;p=484"},"modified":"2026-06-30T17:43:57","modified_gmt":"2026-06-30T17:43:57","slug":"tequila-sunrise-h-309","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/es\/product\/tequila-sunrise-h-309\/","title":{"rendered":"Tequila Sunrise H-309"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cerakote Tequila Sunrise es un naranja ardiente acentuado con met\u00e1licos de color naranja m\u00e1s claro que bailan con la luz.<\/p>\n<p>*NOTA: Este producto viene con un catalizador y requiere un\u00a0<a href=\"https:\/\/www.cerakoteeu.com\/shop\/equipment\/cerakote-in-cup-100-mesh-strainer-150-micron-se-275\/\">Colador de malla 100 (SE-275)<\/a>.<\/p>\n<p>Los recubrimientos Cerakote Serie H son resistentes a la corrosi\u00f3n duradera y proporcionan niveles incomparables de dureza y adherencia. Estos recubrimientos tambi\u00e9n son resistentes a la mayor\u00eda de disolventes y productos qu\u00edmicos. La base de los recubrimientos Cerakote Serie H es una tecnolog\u00eda cer\u00e1mica exclusiva que confiere flexibilidad y una excelente resistencia al desgaste al recubrimiento final. Eche un vistazo a la <a href=\"https:\/\/www.cerakoteeu.com\/documents\/\">Recursos<\/a> para obtener gu\u00edas de aplicaci\u00f3n de productos, fichas t\u00e9cnicas e informaci\u00f3n SDS.<\/p>","protected":false},"featured_media":18108,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[37],"product_tag":[33,192,193,194,196],"class_list":["post-484","product","type-product","status-publish","has-post-thumbnail","product_cat-h-series-coatings","product_tag-cerakote","product_tag-h-309","product_tag-h309","product_tag-orange","product_tag-tequila-sunrise","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/comments?post=484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media\/18108"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media?parent=484"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_brand?post=484"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_cat?post=484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_tag?post=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}