{"id":3369,"date":"2020-04-29T20:41:36","date_gmt":"2020-04-29T20:41:36","guid":{"rendered":"https:\/\/www.cerakote.co.uk\/?post_type=product&#038;p=3369"},"modified":"2026-07-02T12:56:58","modified_gmt":"2026-07-02T12:56:58","slug":"charcoal-green-h-338","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/es\/product\/charcoal-green-h-338\/","title":{"rendered":"Charcoal Green H-338"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cerakote Charcoal Green es un verde\/gris ahumado oscuro resaltado con una escarcha plateada.<\/p>\n<p>*NOTA: Este producto viene con un catalizador y requiere un <a href=\"https:\/\/www.cerakoteeu.com\/product\/cerakote-in-cup-100-mesh-strainer-150-micron-se-275\/\/\"\">Colador de malla 100 (SE-275)<\/a>.<\/p>\n<p>Los recubrimientos Cerakote Serie H son duraderos, resistentes a la corrosi\u00f3n y proporcionan niveles incomparables de dureza y adherencia. Estos recubrimientos tambi\u00e9n son resistentes a la mayor\u00eda de disolventes y productos qu\u00edmicos. La base de los recubrimientos Cerakote Serie H es una tecnolog\u00eda cer\u00e1mica exclusiva que confiere flexibilidad y una excelente resistencia al desgaste al recubrimiento final. Eche un vistazo a la <a href=\"https:\/\/www.cerakoteeu.com\/documents\/\">Recursos<\/a> para obtener gu\u00edas de aplicaci\u00f3n de productos, fichas t\u00e9cnicas e informaci\u00f3n SDS.<\/p>","protected":false},"featured_media":3374,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[37],"product_tag":[33,701,43,36,702],"class_list":["post-3369","product","type-product","status-publish","has-post-thumbnail","product_cat-h-series-coatings","product_tag-cerakote","product_tag-charcoal-green","product_tag-green","product_tag-h-series","product_tag-h-338","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product\/3369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/comments?post=3369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media\/3374"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media?parent=3369"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_brand?post=3369"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_cat?post=3369"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_tag?post=3369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}