{"id":17095,"date":"2024-03-28T15:33:53","date_gmt":"2024-03-28T15:33:53","guid":{"rendered":"https:\/\/www.cerakoteeu.com\/?post_type=product&#038;p=17095"},"modified":"2024-08-05T14:19:19","modified_gmt":"2024-08-05T14:19:19","slug":"glock-42-slide-cerakote-laser-fixture-r-3dp-01-107","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/es\/product\/glock-42-slide-cerakote-laser-fixture-r-3dp-01-107\/","title":{"rendered":"Glock\u00ae 42 Slide - Cerakote\u00ae Laser Fixture - R-3DP-01-107"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Hemos dise\u00f1ado este accesorio para adaptarse a las correderas desmontadas de Glock\u00ae 42. Este accesorio para l\u00e1ser sujeta la corredera en 3 posiciones diferentes, permiti\u00e9ndole grabar con l\u00e1ser ambos lados y la parte superior de la corredera. Esta es una soluci\u00f3n de f\u00e1cil producci\u00f3n para personalizar su Glock con grabado o Cerakote Laser Imaging.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre im\u00e1genes l\u00e1ser, haga clic en <a href=\"https:\/\/www.cerakote.com\/resources\/knowledge-base\/202\/cerakote-laser-imaging\">aqu\u00ed<\/a>.<\/p>\n<p>(Accesorio \u00fanicamente, piezas de armas de fuego no incluidas).<\/p>\n<p>Fijaciones de marco compatibles:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.cerakoteeu.com\/product\/glock-42-frame-cerakote-laser-fixture-r-3dp-01-303\/\">Fijaci\u00f3n l\u00e1ser Cerakote\u00ae - Armaz\u00f3n Glock\u00ae 42<\/a><\/li>\n<\/ul>\n<p>https:\/\/www.youtube.com\/watch?v=V8ePCGs2wsA<\/p>","protected":false},"featured_media":17096,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[106],"product_tag":[1103,1104,1102,1110],"class_list":["post-17095","product","type-product","status-publish","has-post-thumbnail","product_cat-equipment","product_tag-glock","product_tag-laser","product_tag-laser-fixture","product_tag-slide","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product\/17095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/comments?post=17095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media\/17096"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media?parent=17095"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_brand?post=17095"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_cat?post=17095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_tag?post=17095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}