{"id":17053,"date":"2024-03-27T15:07:17","date_gmt":"2024-03-27T15:07:17","guid":{"rendered":"https:\/\/www.cerakoteeu.com\/?post_type=product&#038;p=17053"},"modified":"2024-08-05T14:19:17","modified_gmt":"2024-08-05T14:19:17","slug":"sig-p320-carry-frame-cerakote-laser-fixture-r-3dp-02-301","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/es\/product\/sig-p320-carry-frame-cerakote-laser-fixture-r-3dp-02-301\/","title":{"rendered":"SIG\u00ae P320 Carry Frame - Cerakote\u00ae Laser Fixture - R-3DP-02-301"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Hemos dise\u00f1ado este accesorio para adaptarse a los armazones desmontados de SIG Sauer\u00ae P320 Carry. Este accesorio para l\u00e1ser sujeta el armaz\u00f3n en 5 posiciones diferentes, lo que le permite utilizar el l\u00e1ser en ambos lados, la parte inferior, la parte delantera y la correa trasera. Esta es una soluci\u00f3n de f\u00e1cil producci\u00f3n para personalizar su SIG Sauer con un patr\u00f3n de punteado, grabado o Cerakote Laser Imaging.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre im\u00e1genes l\u00e1ser, haga clic en <a href=\"https:\/\/www.cerakote.com\/resources\/knowledge-base\/202\/cerakote-laser-imaging\">aqu\u00ed<\/a>.<\/p>\n<p>(Accesorio \u00fanicamente, piezas de armas de fuego no incluidas).<\/p>\n<p>Dispositivos de deslizamiento compatibles:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.cerakoteeu.com\/product\/sig-p320-4-7-in-slide-cerakote-laser-fixture-r-3dp-02-101\/\">Cerakote\u00ae Laser Fixture - SIG\u00ae P320 4.7 in Slide<\/a><\/li>\n<li><a href=\"https:\/\/www.cerakoteeu.com\/product\/sig-p320-3-9-in-slide-print-cerakote-laser-fixture-r-3dp-02-102\/\">Cerakote\u00ae Laser Fixture - SIG\u00ae P320 3.9 in Slide<\/a><\/li>\n<\/ul>\n<p>https:\/\/www.youtube.com\/watch?v=V8ePCGs2wsA<\/p>","protected":false},"featured_media":17054,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[106],"product_tag":[1104,1102,1109],"class_list":["post-17053","product","type-product","status-publish","has-post-thumbnail","product_cat-equipment","product_tag-laser","product_tag-laser-fixture","product_tag-p320-carry-frame","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product\/17053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/comments?post=17053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media\/17054"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media?parent=17053"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_brand?post=17053"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_cat?post=17053"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_tag?post=17053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}