{"id":1243,"date":"2019-12-05T15:44:23","date_gmt":"2019-12-05T15:44:23","guid":{"rendered":"https:\/\/staging.cerakote.co.uk\/?post_type=product&#038;p=1243"},"modified":"2026-06-30T17:48:02","modified_gmt":"2026-06-30T17:48:02","slug":"blue-flame-c-158","status":"publish","type":"product","link":"https:\/\/www.cerakoteeu.com\/es\/product\/blue-flame-c-158\/","title":{"rendered":"Blue Flame C-158"},"content":{"rendered":"<section class=\"section\" id=\"section_289498490\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-779102562\">\n\n\t<div id=\"col-1773627743\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong>Datos t\u00e9cnicos del producto:<\/strong><\/p>\n<style>\n.table_component {<br \/>    overflow: auto;<br \/>    width: 100%;<br \/>}<\/p>\n<p>.table_component table {<br \/>    border: 1px solid #dededf;<br \/>    height: 100%;<br \/>    width: 100%;<br \/>    table-layout: fixed;<br \/>    border-collapse: collapse;<br \/>    border-spacing: 1px;<br \/>    text-align: left;<br \/>}<\/p>\n<p>.table_component caption {<br \/>    caption-side: top;<br \/>    text-align: left;<br \/>}<\/p>\n<p>.table_component th {<br \/>    border: 1px solid #dededf;<br \/>    background-color: #eceff1;<br \/>    color: #000000;<br \/>    padding: 5px;<br \/>}<\/p>\n<p>.table_component td {<br \/>    border: 1px solid #dededf;<br \/>    background-color: #ffffff;<br \/>    color: #000000;<br \/>    padding: 5px;<br \/>}<br \/><\/style>\n<div class=\"table_component\" tabindex=\"0\" role=\"region\">\n<table>\n<thead>\n<tr>\n<th><\/th>\n<th><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Calendario de curas<\/td>\n<td>\n<p class=\"p2\">Air Cure: Tack Free 45 &#8211; 60 minutes, Full Cure 5Days<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Espesor recomendado (mil)<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Tama\u00f1o del filtro (malla)<\/td>\n<td>150 (Part # SE-276)<\/td>\n<\/tr>\n<tr>\n<td>Nivel de brillo \/ Unidades (GU)<\/td>\n<td>Eggshell \/ 19<\/td>\n<\/tr>\n<tr>\n<td>Densidad (g\/mL)<\/td>\n<td>1.39<\/td>\n<\/tr>\n<tr>\n<td>% S\u00f3lidos (\u00b12%)<\/td>\n<td>74<\/td>\n<\/tr>\n<tr>\n<td>Viscosidad (cP)<\/td>\n<td>85<\/td>\n<\/tr>\n<tr>\n<td>Rendimiento te\u00f3rico por gal\u00f3n @ espesor recomendado (pies\u00b2)<\/td>\n<td>1188<\/td>\n<\/tr>\n<tr>\n<td>Estabilidad del color (\u00b0F) Max. Temp.<\/td>\n<td>400<\/td>\n<\/tr>\n<tr>\n<td>Resistencia qu\u00edmica<\/td>\n<td>Excelente<\/td>\n<\/tr>\n<tr>\n<td>Estabilidad UV<\/td>\n<td>Excelente<\/td>\n<\/tr>\n<tr>\n<td>Gubia de dureza de l\u00e1piz ASTM D3363<\/td>\n<td>8H<\/td>\n<\/tr>\n<tr>\n<td>Dureza del l\u00e1piz Ara\u00f1azos ASTM D3363<\/td>\n<td>8H<\/td>\n<\/tr>\n<tr>\n<td>Adherencia transversal ASTM D3359<\/td>\n<td>4B<\/td>\n<\/tr>\n<tr>\n<td>Flexibilidad (Resistencia %) Curvatura de mandril c\u00f3nico ASTM D522<\/td>\n<td>98<\/td>\n<\/tr>\n<tr>\n<td>Rendimiento de impacto directo\/indirecto (in-lbs.) ASTM D2794<\/td>\n<td>40\/20<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p data-v-8ef39626=\"\">Todos los resultados se basan en acero granallado recubierto con el espesor recomendado y el programa de curado recomendado.<\/p>\n<p data-v-8ef39626=\"\">*Los niveles de brillo se miden con un \u00e1ngulo de 60\u00b0. Ajustes a las condiciones recomendadas producir\u00e1n resultados diferentes. El brillo se ve afectado por la calidad de la preparaci\u00f3n y la t\u00e9cnica de pulverizaci\u00f3n. Los resultados se basan en acero granallado recubierto curado seg\u00fan la especificaci\u00f3n del Programa de curado.<\/p>\n<p data-v-8ef39626=\"\">**Viscosidad medida en condiciones ambientales (temperatura del aire, humedad relativa) en el momento de la fabricaci\u00f3n.<\/p>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Temperatura de curado recomendada:<\/strong><\/p>\n<ul data-v-8ef39626=\"\">\n<li data-v-8ef39626=\"\">Consulte la especificaci\u00f3n del programa de curado disponible en cada producto Cerakote.<\/li>\n<\/ul>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Temperatura m\u00e1xima<\/strong>\u00a0es la temperatura a la que el color o el revestimiento son estables.<\/p>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Pruebas de resistencia qu\u00edmica:<\/strong>\u00a0Los resultados se refieren al cambio de color basado en la formulaci\u00f3n CIE76. Los resultados oscilan entre:<\/p>\n<ul data-v-8ef39626=\"\">\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Excelente:<\/strong>\u00a0\u2206E cambio de &lt;2,5<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Bien:<\/strong>\u00a0\u2206E cambio de &lt;3,0<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Justo:<\/strong>\u00a0\u2206E cambio de &lt;3,5<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Pobre:<\/strong>\u00a0\u2206E cambio de &lt;4,0<\/li>\n<\/ul>\n<p data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Los par\u00e1metros de ensayo son los siguientes:<\/strong><\/p>\n<ul data-v-8ef39626=\"\">\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Dureza<\/strong>\u00a0o Las pruebas de dureza de los l\u00e1pices se miden del m\u00e1s blando al m\u00e1s duro de la siguiente manera: 9B, 8B, 7B, 6B, 5B, 4B, 3B, 2B, B, HB, F, H, 2H, 3H, 4H, 5H, 6H, 7H, 8H, 9H. 9H es el m\u00e1s dif\u00edcil.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">S\u00d3LO SG-100:<\/strong>\u00a0Prueba de dureza M\u00e9todo A - Se realiza un corte en X a trav\u00e9s de la pel\u00edcula hasta el sustrato, se aplica cinta adhesiva sensible a la presi\u00f3n sobre el corte y luego se retira, y se eval\u00faa cualitativamente la adherencia en una escala de 0 a 5.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Adhesi\u00f3n<\/strong>\u00a0se mide en una escala de 0B, 1B, 2B, 3B, 4B, 5B, siendo 5B la calificaci\u00f3n m\u00e1s alta alcanzable.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Flexibilidad<\/strong>\u00a0o curvatura de mandril c\u00f3nico: \"Resistencia 100%\" es la calificaci\u00f3n m\u00e1s alta alcanzable e indica que el revestimiento no se agriet\u00f3 ni se desprendi\u00f3.<\/li>\n<li data-v-8ef39626=\"\"><strong data-v-8ef39626=\"\">Impacto (directo\/indirecto)<\/strong>\u00a0se mide en una escala de 0 pulg.-lbs. a 160 pulg.-lbs., siendo 160 pulg.-lbs. el valor m\u00e1s alto alcanzable.<\/li>\n<\/ul>\n<p data-v-8ef39626=\"\">Todos los recubrimientos Cerakote cumplen la normativa COV de la EPA y tienen un contenido bajo o nulo de COV. Para conocer el contenido de COV de un recubrimiento individual, p\u00f3ngase en contacto con\u00a0<a href=\"mailto:sds@nicindustries.com\" target=\"_blank\" rel=\"noopener\" data-v-8ef39626=\"\">sds@nicindustries.com<\/a>\u00a0para m\u00e1s informaci\u00f3n.<\/p>\n<p data-v-8ef39626=\"\">Esta informaci\u00f3n es exacta a nuestro leal saber y entender, sin embargo, no constituir\u00e1 garant\u00eda de ninguna caracter\u00edstica espec\u00edfica del producto ni establecer\u00e1 una relaci\u00f3n contractual legalmente v\u00e1lida. Le recomendamos que realice las pruebas adecuadas en sus instalaciones para determinar si este producto cumple todos sus requisitos.<\/p>\n<p data-v-8ef39626=\"\">No dude en enviarnos un correo electr\u00f3nico a <a href=\"mailto:enquiries@cerakoteeu.com\" target=\"_blank\" rel=\"noopener\" data-v-8ef39626=\"\">enquiries@cerakoteeu.com<\/a>\u00a0 si tiene alguna pregunta.<\/p>\n<\/div>\n<div class=\"row\"  id=\"row-1865529325\">\n\n\t<div id=\"col-1754841598\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/images.nicindustries.com\/cerakote\/documents\/6998\/cerakote-c-series-dt20241219191346710211.pdf?1734635628&#038;_gl=1*17xq0fw*_gcl_au*MTA5MjM2ODk3NS4xNzUwMzE5ODc4*_ga*MTk4NjI1NzI1OC4xNzAzMTU2NTIz*_ga_KPM5Q2PRTX*czE3NTM0Mjk3NzgkbzM4JGcxJHQxNzUzNDMxMjg3JGo2MCRsMCRoMjMyNjIzNjk4\" target=\"_blank\" class=\"button primary\" rel=\"noopener\" >\n\t\t<span>Ficha de datos de seguridad<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1978631066\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/images.nicindustries.com\/cerakote\/documents\/7366\/c-series-training-manual-air-cure-dt2025052120523612731.pdf?1747860761&#038;_gl=1*1jpg8b3*_gcl_au*MTA5MjM2ODk3NS4xNzUwMzE5ODc4*_ga*MTk4NjI1NzI1OC4xNzAzMTU2NTIz*_ga_KPM5Q2PRTX*czE3NTM0Mjk3NzgkbzM4JGcxJHQxNzUzNDMxMjk1JGo1MiRsMCRoMjMyNjIzNjk4\" target=\"_blank\" class=\"button primary\" rel=\"noopener\" >\n\t\t<span>Gu\u00eda de aplicaci\u00f3n<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1550035040\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/www.cerakoteeu.com\/wp-content\/uploads\/2025\/07\/C-158-Blue-Flame.pdf\" target=\"_blank\" class=\"button primary\" rel=\"noopener\" >\n\t\t<span>Ficha t\u00e9cnica<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_289498490 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"<p>Cerakote Blue Flame es un azul zafiro intenso y un revestimiento ex\u00f3tico de la serie C.<\/p>\n<p>*NOTA: Este producto no requiere catalizador. Este color s\u00ed requiere un\u00a0<a href=\"https:\/\/www.cerakoteeu.com\/product\/cerakote-in-cup-150-mesh-strainer-100-micron-se-276\/\">Colador de malla 150<\/a> (SE-276).<\/p>\n<p>Los recubrimientos cer\u00e1micos Cerakote Blue Flame Serie C funcionan a temperaturas de hasta 800\u00b0F \/ 426\u00b0C y establecen el est\u00e1ndar de la industria en recubrimientos de alta temperatura. Los recubrimientos de la Serie C son una l\u00ednea de recubrimientos cer\u00e1micos curados al aire y listos para pulverizar. Eche un vistazo a la <a href=\"https:\/\/www.cerakoteeu.com\/documents\/\">Recursos<\/a> para obtener gu\u00edas de aplicaci\u00f3n de productos, fichas t\u00e9cnicas e informaci\u00f3n SDS.<\/p>","protected":false},"featured_media":6044,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1120,987,1124,1123],"product_tag":[212,496,497,59,33],"class_list":["post-1243","product","type-product","status-publish","has-post-thumbnail","product_cat-c-series-coatings","product_cat-cerakote-coatings","product_cat-up-to-260c","product_cat-up-to-425c","product_tag-blue","product_tag-blue-flame","product_tag-c-158","product_tag-c-series","product_tag-cerakote","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product\/1243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/comments?post=1243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media\/6044"}],"wp:attachment":[{"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/media?parent=1243"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_brand?post=1243"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_cat?post=1243"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cerakoteeu.com\/es\/wp-json\/wp\/v2\/product_tag?post=1243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}